{"id":115,"date":"2024-08-06T02:38:20","date_gmt":"2024-08-06T00:38:20","guid":{"rendered":"https:\/\/diasporaweb.de\/index.php\/passwort\/"},"modified":"2024-08-14T14:37:58","modified_gmt":"2024-08-14T12:37:58","slug":"passwort","status":"publish","type":"page","link":"https:\/\/diasporaweb.de\/de\/passwort\/","title":{"rendered":"Gesetzliche Haftung"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.16&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;#393e56 0%|rgba(57,62,86,0.82) 100%&#8220; background_color_gradient_overlays_image=&#8220;on&#8220; background_color_gradient_start=&#8220;#393e56&#8243; background_color_gradient_end=&#8220;rgba(57,62,86,0.82)&#8220; background_image=&#8220;https:\/\/diasporaweb.de\/wp-content\/uploads\/2024\/08\/political-candidate-40.jpg&#8220; custom_margin=&#8220;|||&#8220; custom_padding=&#8220;||10vw||false|false&#8220; bottom_divider_style=&#8220;wave2&#8243; bottom_divider_color=&#8220;#ffffff&#8220; bottom_divider_height=&#8220;10vw&#8220; bottom_divider_repeat=&#8220;0.5x&#8220; bottom_divider_flip=&#8220;vertical|horizontal&#8220; bottom_divider_arrangement=&#8220;above_content&#8220; bottom_divider_height_tablet=&#8220;0px&#8220; bottom_divider_height_phone=&#8220;0px&#8220; bottom_divider_height_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1><span style=\"color: #ffff99;\">Hinweis auf der Website<\/span><\/h1>\n<h1><span style=\"color: #ffff99;\">Impressum<\/span><\/h1>\n<h1><span style=\"color: #ffff99;\">Hinweis zur Website<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; prev_background_color=&#8220;#ffffff&#8220; admin_label=&#8220;Events&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#f5f5f5&#8243; use_background_color_gradient=&#8220;on&#8220; background_color_gradient_stops=&#8220;#f5f5f5 0%|#ffffff 100%&#8220; background_color_gradient_start=&#8220;#f5f5f5&#8243; background_color_gradient_end=&#8220;#ffffff&#8220; custom_margin=&#8220;|||&#8220; custom_margin_tablet=&#8220;|0px||&#8220; custom_margin_last_edited=&#8220;off|desktop&#8220; custom_padding=&#8220;0vw||54px||false|false&#8220; top_divider_style=&#8220;wave2&#8243; top_divider_height=&#8220;14vw&#8220; top_divider_repeat=&#8220;0.5x&#8220; top_divider_flip=&#8220;horizontal&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>Hinweis auf der Website<\/strong><\/p>\n<p><strong>Medien Present KOS LLC<\/strong><br \/>M\u00e4rtyrer der Nation Boulevardplatz Nr. 72,9<br \/>10000 Pristina<\/p>\n<p><strong>Handelsregister:<\/strong> 812183664<br \/><strong>Registergericht:<\/strong> Ministerium f\u00fcr Industrie, Unternehmertum und Handel<\/p>\n<p><strong>Vertreten durch:<\/strong><br \/>Andi Jakupi<\/p>\n<p><strong>Kontakt<\/strong><\/p>\n<p>Telefon: +383 48 758768<br \/>E-Mail: <a rel=\"noreferrer\">info@diasporaweb.de<\/a><\/p>\n<p><strong>Umsatzsteuer-ID<\/strong><\/p>\n<p>Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:<br \/>812183664<\/p>\n<p><strong>Verantwortlicher f\u00fcr die Redaktion<\/strong><\/p>\n<p><strong>Medien Present KOS LLC<\/strong><br \/>M\u00e4rtyrer der Nation Boulevardplatz Nr. 72,9<br \/><a rel=\"noreferrer\">info@diasporaweb.de<\/a><\/p>\n<p><strong>Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle<\/strong><\/p>\n<p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_divider _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|tablet&#8220; admin_label=&#8220;Vote&#8220; _builder_version=&#8220;4.16&#8243; background_image=&#8220;https:\/\/diasporaweb.de\/wp-content\/uploads\/2024\/08\/political-candidate-37.png&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_center&#8220; custom_padding=&#8220;120px||0||false|false&#8220; custom_padding_tablet=&#8220;40px|||&#8220; custom_padding_phone=&#8220;&#8220; bottom_divider_style=&#8220;wave2&#8243; bottom_divider_color=&#8220;#ffffff&#8220; bottom_divider_height=&#8220;10vw&#8220; bottom_divider_repeat=&#8220;0.5x&#8220; bottom_divider_flip=&#8220;vertical|horizontal&#8220; bottom_divider_arrangement=&#8220;above_content&#8220; bottom_divider_height_tablet=&#8220;0px&#8220; bottom_divider_height_phone=&#8220;0px&#8220; bottom_divider_height_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hinweis auf der Website Impressum Hinweis zur WebsiteHinweis auf der Website Medien Present KOS LLCM\u00e4rtyrer der Nation Boulevardplatz Nr. 72,910000 Pristina Handelsregister: 812183664Registergericht: Ministerium f\u00fcr Industrie, Unternehmertum und Handel Vertreten durch:Andi Jakupi Kontakt Telefon: +383 48 758768E-Mail: info@diasporaweb.de Umsatzsteuer-ID Umsatzsteuer-Identifikationsnummer gem\u00e4\u00df \u00a7 27 a Umsatzsteuergesetz:812183664 Verantwortlicher f\u00fcr die Redaktion Medien Present KOS LLCM\u00e4rtyrer der Nation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-115","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/pages\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":7,"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/pages\/115\/revisions"}],"predecessor-version":[{"id":648,"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/pages\/115\/revisions\/648"}],"wp:attachment":[{"href":"https:\/\/diasporaweb.de\/de\/wp-json\/wp\/v2\/media?parent=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}